{"id":36969,"date":"2026-06-30T14:36:00","date_gmt":"2026-06-30T14:36:00","guid":{"rendered":"https:\/\/artslibris.cat\/?post_type=product&#038;p=36969"},"modified":"2026-06-30T14:36:02","modified_gmt":"2026-06-30T14:36:02","slug":"futebol-urban-euphoria-in-brazil","status":"publish","type":"product","link":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/","title":{"rendered":"Futebol: urban Euphoria in Brazil"},"content":{"rendered":"<p data-path-to-node=\"2\">En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un <i data-path-to-node=\"2\" data-index-in-node=\"571\">campo de pelada<\/i>. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.<\/p>\n<p data-path-to-node=\"3\">Leonardo Finotti crea una especie de inventario, mostrando im\u00e1genes de su serie <i data-path-to-node=\"3\" data-index-in-node=\"80\">Campos Sagrados<\/i>, para la cual viaj\u00f3 por todo Brasil \u2014a barrios ricos y pobres, a zonas industriales, periferias urbanas y al campo\u2014 para tomar fotograf\u00edas desde una perspectiva elevada de campos de f\u00fatbol, tanto temporales como &#8220;reales&#8221;, y de sus alrededores.<\/p>\n<p data-path-to-node=\"4\">En su serie fotogr\u00e1fica <i data-path-to-node=\"4\" data-index-in-node=\"24\">Brasileiros Futebol Clube<\/i>, Ed Viggiani acompa\u00f1a a sus compatriotas a cualquier lugar donde se juegue al f\u00fatbol o se siga a un equipo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo: Futebol: urban Euphoria in Brazil<\/p>\n<p>Autores: Leonardo Finotti<\/p>\n<p>Editorial: Lars M\u00fcller<\/p>\n<p>A\u00f1o de publicaci\u00f3n: 2014<\/p>\n<p>ISBN: 978-3-03778-431-0<\/p>\n","protected":false},"featured_media":36970,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[34],"product_tag":[674],"class_list":["post-36969","product","type-product","status-publish","has-post-thumbnail","product_cat-fotolibro","product_tag-lars-muller","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Futebol: urban Euphoria in Brazil - ArtsLibris<\/title>\n<meta name=\"description\" content=\"En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un campo de pelada. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futebol: urban Euphoria in Brazil - ArtsLibris\" \/>\n<meta property=\"og:description\" content=\"En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un campo de pelada. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/\" \/>\n<meta property=\"og:site_name\" content=\"ArtsLibris\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/artslibris\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T14:36:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/71C1MICVccL._SL1142_.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"846\" \/>\n\t<meta property=\"og:image:height\" content=\"1142\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArtsLibris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/\",\"name\":\"Futebol: urban Euphoria in Brazil - ArtsLibris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/71C1MICVccL._SL1142_.webp\",\"datePublished\":\"2026-06-30T14:36:00+00:00\",\"dateModified\":\"2026-06-30T14:36:02+00:00\",\"description\":\"En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un campo de pelada. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/71C1MICVccL._SL1142_.webp\",\"contentUrl\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/71C1MICVccL._SL1142_.webp\",\"width\":846,\"height\":1142},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/tienda\\\/fotolibro-en\\\/futebol-urban-euphoria-in-brazil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Futebol: urban Euphoria in Brazil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/\",\"name\":\"ArtsLibris\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/#organization\",\"name\":\"ArtsLibris\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ArtsLibris-logo-black.svg\",\"contentUrl\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ArtsLibris-logo-black.svg\",\"width\":521,\"height\":85,\"caption\":\"ArtsLibris\"},\"image\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/artslibris\\\/\",\"https:\\\/\\\/x.com\\\/ArtsLibris\",\"https:\\\/\\\/www.instagram.com\\\/artslibris\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Futebol: urban Euphoria in Brazil - ArtsLibris","description":"En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un campo de pelada. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/","og_locale":"en_US","og_type":"article","og_title":"Futebol: urban Euphoria in Brazil - ArtsLibris","og_description":"En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un campo de pelada. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.","og_url":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/","og_site_name":"ArtsLibris","article_publisher":"https:\/\/www.facebook.com\/artslibris\/","article_modified_time":"2026-06-30T14:36:02+00:00","og_image":[{"width":846,"height":1142,"url":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/71C1MICVccL._SL1142_.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@ArtsLibris","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/","url":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/","name":"Futebol: urban Euphoria in Brazil - ArtsLibris","isPartOf":{"@id":"https:\/\/artslibris.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/#primaryimage"},"image":{"@id":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/#primaryimage"},"thumbnailUrl":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/71C1MICVccL._SL1142_.webp","datePublished":"2026-06-30T14:36:00+00:00","dateModified":"2026-06-30T14:36:02+00:00","description":"En Brasil, el f\u00fatbol es m\u00e1s que un simple deporte. Es la esperanza de un futuro mejor, una distracci\u00f3n de la vida cotidiana, un creador de identidad y comunidad. Si no hay un bal\u00f3n cerca, la gente patea frutas o latas; cuando no hay una cancha, la improvisan. El f\u00fatbol marca el alma del pueblo brasile\u00f1o, as\u00ed como la imagen de la ciudad y el paisaje. Cualquier terreno que est\u00e9 m\u00e1s o menos nivelado, y que no est\u00e9 cubierto de maleza o edificado, se convierte en un campo de f\u00fatbol. Aunque puedan faltar lugares de reuni\u00f3n, parques o centros comunitarios, siempre hay un campo de pelada. En este volumen, dos fot\u00f3grafos brasile\u00f1os buscan y encuentran el f\u00fatbol en lugares donde uno no esperar\u00eda hallarlo.","breadcrumb":{"@id":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/#primaryimage","url":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/71C1MICVccL._SL1142_.webp","contentUrl":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/71C1MICVccL._SL1142_.webp","width":846,"height":1142},{"@type":"BreadcrumbList","@id":"https:\/\/artslibris.cat\/en\/tienda\/fotolibro-en\/futebol-urban-euphoria-in-brazil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/artslibris.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/artslibris.cat\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Futebol: urban Euphoria in Brazil"}]},{"@type":"WebSite","@id":"https:\/\/artslibris.cat\/en\/#website","url":"https:\/\/artslibris.cat\/en\/","name":"ArtsLibris","description":"","publisher":{"@id":"https:\/\/artslibris.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artslibris.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/artslibris.cat\/en\/#organization","name":"ArtsLibris","url":"https:\/\/artslibris.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/artslibris.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/artslibris.cat\/wp-content\/uploads\/2020\/05\/ArtsLibris-logo-black.svg","contentUrl":"https:\/\/artslibris.cat\/wp-content\/uploads\/2020\/05\/ArtsLibris-logo-black.svg","width":521,"height":85,"caption":"ArtsLibris"},"image":{"@id":"https:\/\/artslibris.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/artslibris\/","https:\/\/x.com\/ArtsLibris","https:\/\/www.instagram.com\/artslibris\/"]}]}},"_links":{"self":[{"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/product\/36969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/media\/36970"}],"wp:attachment":[{"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/media?parent=36969"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/product_brand?post=36969"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/product_cat?post=36969"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artslibris.cat\/en\/wp-json\/wp\/v2\/product_tag?post=36969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}