{"id":36546,"date":"2026-06-24T09:12:05","date_gmt":"2026-06-24T09:12:05","guid":{"rendered":"https:\/\/artslibris.cat\/?post_type=product&#038;p=36546"},"modified":"2026-06-24T09:12:06","modified_gmt":"2026-06-24T09:12:06","slug":"futuros-abundantes-abundant-futures","status":"publish","type":"product","link":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/","title":{"rendered":"Futuros abundantes \/ Abundant Futures"},"content":{"rendered":"<p>Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.<\/p>\n<p>Completamente ilustrado, el libro re\u00fane una multitud de voces y pr\u00e1cticas art\u00edsticas, intervenciones, poes\u00eda, textos recientemente comisariados y una rica selecci\u00f3n de fotograf\u00edas de la exposici\u00f3n y las performances. Adem\u00e1s, propone un sugestivo debate sobre los temas de la abundancia, la escasez, y el conflicto entre ecolog\u00eda y naturaleza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo: Futuros abundantes \/ Abundant Futures<\/p>\n<p>Autor: Daniela Zyman y Eva Ebersberger<\/p>\n<p>Editorial: Turner<\/p>\n<p>P\u00e1ginas: 336<\/p>\n<p>ISBN: <span class=\"pa_isbn\">978-84-19539-01-4<\/span><\/p>\n","protected":false},"featured_media":36547,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[554,98],"product_tag":[305],"class_list":["post-36546","product","type-product","status-publish","has-post-thumbnail","product_cat-exposicion","product_cat-catalogo","product_tag-turner","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Futuros abundantes \/ Abundant Futures - ArtsLibris<\/title>\n<meta name=\"description\" content=\"Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futuros abundantes \/ Abundant Futures - ArtsLibris\" \/>\n<meta property=\"og:description\" content=\"Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/\" \/>\n<meta property=\"og:site_name\" content=\"ArtsLibris\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/artslibris\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T09:12:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/Futuros-abundantes-scaled-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1982\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ArtsLibris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/\",\"name\":\"Futuros abundantes \\\/ Abundant Futures - ArtsLibris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Futuros-abundantes-scaled-1.webp\",\"datePublished\":\"2026-06-24T09:12:05+00:00\",\"dateModified\":\"2026-06-24T09:12:06+00:00\",\"description\":\"Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/#primaryimage\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Futuros-abundantes-scaled-1.webp\",\"contentUrl\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Futuros-abundantes-scaled-1.webp\",\"width\":1982,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tienda\\\/catalogo-ca\\\/futuros-abundantes-abundant-futures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tenda\",\"item\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/tenda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Futuros abundantes \\\/ Abundant Futures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/\",\"name\":\"ArtsLibris\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/#organization\",\"name\":\"ArtsLibris\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ArtsLibris-logo-black.svg\",\"contentUrl\":\"https:\\\/\\\/artslibris.cat\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ArtsLibris-logo-black.svg\",\"width\":521,\"height\":85,\"caption\":\"ArtsLibris\"},\"image\":{\"@id\":\"https:\\\/\\\/artslibris.cat\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/artslibris\\\/\",\"https:\\\/\\\/x.com\\\/ArtsLibris\",\"https:\\\/\\\/www.instagram.com\\\/artslibris\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Futuros abundantes \/ Abundant Futures - ArtsLibris","description":"Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/","og_locale":"ca_ES","og_type":"article","og_title":"Futuros abundantes \/ Abundant Futures - ArtsLibris","og_description":"Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.","og_url":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/","og_site_name":"ArtsLibris","article_publisher":"https:\/\/www.facebook.com\/artslibris\/","article_modified_time":"2026-06-24T09:12:06+00:00","og_image":[{"width":1982,"height":2560,"url":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/Futuros-abundantes-scaled-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@ArtsLibris","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/","url":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/","name":"Futuros abundantes \/ Abundant Futures - ArtsLibris","isPartOf":{"@id":"https:\/\/artslibris.cat\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/#primaryimage"},"image":{"@id":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/#primaryimage"},"thumbnailUrl":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/Futuros-abundantes-scaled-1.webp","datePublished":"2026-06-24T09:12:05+00:00","dateModified":"2026-06-24T09:12:06+00:00","description":"Esta publicaci\u00f3n aborda la propuesta formulada a trav\u00e9s de la exposici\u00f3n Futuros abundantes que presenta un intento audaz de imaginar la creaci\u00f3n de mundos y los futuros ecol\u00f3gicos desde la condici\u00f3n de abundancia y plenitud. Pone en conversaci\u00f3n numerosas visiones y propuestas art\u00edsticas de la colecci\u00f3n TBA21 Thyssen Bornemisza Art Contemporary, se\u00f1alando la multiplicidad de mundos en los que cohabitan humanos y no humanos, un mundo de muchos mundos.","breadcrumb":{"@id":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/#primaryimage","url":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/Futuros-abundantes-scaled-1.webp","contentUrl":"https:\/\/artslibris.cat\/wp-content\/uploads\/2026\/06\/Futuros-abundantes-scaled-1.webp","width":1982,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/artslibris.cat\/ca\/tienda\/catalogo-ca\/futuros-abundantes-abundant-futures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/artslibris.cat\/ca\/"},{"@type":"ListItem","position":2,"name":"Tenda","item":"https:\/\/artslibris.cat\/ca\/tenda\/"},{"@type":"ListItem","position":3,"name":"Futuros abundantes \/ Abundant Futures"}]},{"@type":"WebSite","@id":"https:\/\/artslibris.cat\/ca\/#website","url":"https:\/\/artslibris.cat\/ca\/","name":"ArtsLibris","description":"","publisher":{"@id":"https:\/\/artslibris.cat\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artslibris.cat\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/artslibris.cat\/ca\/#organization","name":"ArtsLibris","url":"https:\/\/artslibris.cat\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/artslibris.cat\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/artslibris.cat\/wp-content\/uploads\/2020\/05\/ArtsLibris-logo-black.svg","contentUrl":"https:\/\/artslibris.cat\/wp-content\/uploads\/2020\/05\/ArtsLibris-logo-black.svg","width":521,"height":85,"caption":"ArtsLibris"},"image":{"@id":"https:\/\/artslibris.cat\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/artslibris\/","https:\/\/x.com\/ArtsLibris","https:\/\/www.instagram.com\/artslibris\/"]}]}},"_links":{"self":[{"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/product\/36546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/media\/36547"}],"wp:attachment":[{"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/media?parent=36546"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/product_brand?post=36546"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/product_cat?post=36546"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artslibris.cat\/ca\/wp-json\/wp\/v2\/product_tag?post=36546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}